{"id":2678,"date":"2019-01-30T12:25:38","date_gmt":"2019-01-30T12:25:38","guid":{"rendered":"https:\/\/filtext.com\/?p=2678"},"modified":"2019-02-04T14:29:51","modified_gmt":"2019-02-04T14:29:51","slug":"tecniques-empaquetatge","status":"publish","type":"post","link":"https:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge","title":{"rendered":"T\u00e9cnicas d&#8217;empaquetatge: el retractilat"},"content":{"rendered":"<h1><span style=\"font-size: 18pt;\"><strong>Descobreix la import\u00e0ncia de les t\u00e8cniques d&#8217;empaquetatge amb el retractilat<\/strong><\/span><\/h1>\n<p>Vol descobrir una de les t\u00e8cniques d&#8217;embalatge m\u00e9s usades en el sector del packaging? A Filtext portem m\u00e9s de 20 anys treballant en proc\u00e9s <a href=\"https:\/\/filtext.com\/ca\/etiquetatge-i-embalatge\" target=\"_blank\" rel=\"noopener\">d&#8217;empaquetatge i etiquetatge<\/a>. Amb l&#8217;experi\u00e8ncia, hem descobert tots els secrets que no et pots perdre. Per a aix\u00f2 avui us desvetllarem una de les t\u00e8cniques d&#8217;embalatge m\u00e9s usades: el retractilat.<\/p>\n<h2><span style=\"font-size: 14pt;\"><strong>Les t\u00e8cniques d&#8217;empaquetatge, una de les fases m\u00e9s importants en la cadena de producci\u00f3<\/strong><\/span><\/h2>\n<p>Les t\u00e8cniques d&#8217;empaquetatge s\u00f3n una de les fases m\u00e9s rellevants de la cadena producci\u00f3. Aquestes operacions es poden usar per a qualsevol recipient que est\u00e0 en contacte directe o indirecte amb el producte, amb l&#8217;objectiu de protegir-lo i conservar-lo, facilitant el seu maneig, transport o emmagatzematge.<\/p>\n<p>Existeixen nombroses t\u00e8cniques segons la finalitat del client. A <a href=\"https:\/\/filtext.com\/ca\" target=\"_blank\" rel=\"noopener\">Filtext<\/a> ens adaptem per dur a terme tots els processos de fabricaci\u00f3 i dissenyar empaquetatges complint les necessitats dels usuaris.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2636\" title=\"t\u00e9cnicas de empaquetado \" src=\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1-300x225.jpg\" alt=\"t\u00e9cniques d'empaquetatge\" width=\"408\" height=\"306\" \/><\/p>\n<h2><strong><span style=\"font-size: 14pt;\">Els secrets del retractilat<\/span><\/strong><\/h2>\n<p>El retractilat \u00e9s una de les t\u00e8cniques d&#8217;empaquetatge m\u00e9s usades en el m\u00f3n del packaging. El seu proc\u00e9s consisteix a embolicar un objecte amb un film termopl\u00e0stic transparent que s&#8217;ajusta perfectament a la seva superf\u00edcie. Un cop s&#8217;aplica correctament aquest material de pl\u00e0stic al disseny requerit, se li aplica el color en el seu contorn de forma equilibrada per poder oferir el producte final que el client desitgi.<\/p>\n<p>Per dur a terme les t\u00e8cniques d&#8217;empaquetat necessitem una maquin\u00e0ria espec\u00edfica. En Filtext comptem amb totes les eines necess\u00e0ries per poder adaptar-nos a les demandes dels clients.<\/p>\n<h2><span style=\"font-size: 14pt;\"><strong>Per a qu\u00e8 s&#8217;usa el retractilat?<\/strong><\/span><\/h2>\n<p><img decoding=\"async\" class=\"wp-image-2633 alignright\" title=\"t\u00e9cnicas de empaquetado \" src=\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656.jpg\" alt=\"\" width=\"279\" height=\"372\" srcset=\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656-18x24.jpg 18w, https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656-27x36.jpg 27w, https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656-36x48.jpg 36w, https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656-200x267.jpg 200w, https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656-225x300.jpg 225w, https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114908-e1548154692656.jpg 245w\" sizes=\"(max-width: 279px) 100vw, 279px\" \/><\/p>\n<p>El retractilat \u00e9s una de les t\u00e8cniques d&#8217;embalatge m\u00e9s usades per al packaging.<\/p>\n<p>S&#8217;utilitza pel packaging de de revistes, diaris, llibres o llibretes. Gr\u00e0cies a aquest material de pl\u00e0stic transparent, els clients poden veure el que hi ha a l&#8217;interior. Aix\u00ed mateix, est\u00e0 operaci\u00f3 tamb\u00e9 \u00e9s molt usat per elaborar empaquetatges per al sector de l&#8217;alimentaci\u00f3 amb la finalitat de protegir productes de l&#8217;exterior.<\/p>\n<p>L&#8217;empaquetatge del producte juga un paper molt important per al proc\u00e9s de compra final del client. En Filtext som especialistes en el desenvolupament de tot aquest proc\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/filtext.com\/ca\/contacte-serveis-filtext\" target=\"_blank\" rel=\"noopener\">Contacta amb el nostre equip directiu<\/a> i aconsegueix m\u00e9s informaci\u00f3 sobre les t\u00e8cniques d&#8217;empaquetat.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descobreix la import\u00e0ncia de les t\u00e8cniques d&#8217;empaquetatge amb el retractilat Vol descobrir una de les t\u00e8cniques d&#8217;embalatge m\u00e9s usades en el sector del packaging? A Filtext portem m\u00e9s de 20 anys treballant en proc\u00e9s d&#8217;empaquetatge i etiquetatge. Amb l&#8217;experi\u00e8ncia, hem descobert tots els secrets que no et pots perdre. Per a aix\u00f2 avui us desvetllarem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,60],"tags":[380,365],"class_list":["post-2678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-corporatiu","tag-filtext98-ca","tag-maquinaria-externa-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e8cniques d&#039;Empaquetatge | El Proc\u00e9s de Retractilat | Filtext<\/title>\n<meta name=\"description\" content=\"El retractilat \u00e9s una de les t\u00e8cniques d&#039;embalatge m\u00e9s usades en el m\u00f3n del packaging. Existeixen nombroses t\u00e8cniques segons la finalitat del client.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e8cniques d&#039;Empaquetatge | El Proc\u00e9s de Retractilat | Filtext\" \/>\n<meta property=\"og:description\" content=\"El retractilat \u00e9s una de les t\u00e8cniques d&#039;embalatge m\u00e9s usades en el m\u00f3n del packaging. Existeixen nombroses t\u00e8cniques segons la finalitat del client.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\" \/>\n<meta property=\"og:site_name\" content=\"Filtext\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T12:25:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-04T14:29:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Filtext\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filtext\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#article\",\"isPartOf\":{\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\"},\"author\":{\"name\":\"Filtext\",\"@id\":\"https:\/\/filtext.com\/#\/schema\/person\/8661f6ef084de4ea654250e1bc9b0391\"},\"headline\":\"T\u00e9cnicas d&#8217;empaquetatge: el retractilat\",\"datePublished\":\"2019-01-30T12:25:38+00:00\",\"dateModified\":\"2019-02-04T14:29:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/filtext.com\/#organization\"},\"image\":{\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage\"},\"thumbnailUrl\":\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg\",\"keywords\":[\"Filtext98\",\"Maquinaria Externa\"],\"articleSection\":[\"Blog\",\"Corporatiu\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\",\"url\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\",\"name\":\"T\u00e8cniques d'Empaquetatge | El Proc\u00e9s de Retractilat | Filtext\",\"isPartOf\":{\"@id\":\"https:\/\/filtext.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage\"},\"image\":{\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage\"},\"thumbnailUrl\":\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg\",\"datePublished\":\"2019-01-30T12:25:38+00:00\",\"dateModified\":\"2019-02-04T14:29:51+00:00\",\"description\":\"El retractilat \u00e9s una de les t\u00e8cniques d'embalatge m\u00e9s usades en el m\u00f3n del packaging. Existeixen nombroses t\u00e8cniques segons la finalitat del client.\",\"breadcrumb\":{\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage\",\"url\":\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg\",\"contentUrl\":\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg\",\"width\":4000,\"height\":3000,\"caption\":\"t\u00e8cniques d'empaquetat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/filtext.com\/ca\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9cnicas d&#8217;empaquetatge: el retractilat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/filtext.com\/#website\",\"url\":\"https:\/\/filtext.com\/\",\"name\":\"Filtext\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/filtext.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/filtext.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/filtext.com\/#organization\",\"name\":\"Filtext98\",\"url\":\"https:\/\/filtext.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/filtext.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/02\/Logo-Filtext.png\",\"contentUrl\":\"https:\/\/filtext.com\/wp-content\/uploads\/2019\/02\/Logo-Filtext.png\",\"width\":300,\"height\":88,\"caption\":\"Filtext98\"},\"image\":{\"@id\":\"https:\/\/filtext.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/filtext.com\/#\/schema\/person\/8661f6ef084de4ea654250e1bc9b0391\",\"name\":\"Filtext\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/filtext.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a4ee48e540dc455f239742316dc3194?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a4ee48e540dc455f239742316dc3194?s=96&d=mm&r=g\",\"caption\":\"Filtext\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e8cniques d'Empaquetatge | El Proc\u00e9s de Retractilat | Filtext","description":"El retractilat \u00e9s una de les t\u00e8cniques d'embalatge m\u00e9s usades en el m\u00f3n del packaging. Existeixen nombroses t\u00e8cniques segons la finalitat del client.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge","og_locale":"ca_ES","og_type":"article","og_title":"T\u00e8cniques d'Empaquetatge | El Proc\u00e9s de Retractilat | Filtext","og_description":"El retractilat \u00e9s una de les t\u00e8cniques d'embalatge m\u00e9s usades en el m\u00f3n del packaging. Existeixen nombroses t\u00e8cniques segons la finalitat del client.","og_url":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge","og_site_name":"Filtext","article_published_time":"2019-01-30T12:25:38+00:00","article_modified_time":"2019-02-04T14:29:51+00:00","og_image":[{"width":1024,"height":768,"url":"http:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1-1024x768.jpg","type":"image\/jpeg"}],"author":"Filtext","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Filtext","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#article","isPartOf":{"@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge"},"author":{"name":"Filtext","@id":"https:\/\/filtext.com\/#\/schema\/person\/8661f6ef084de4ea654250e1bc9b0391"},"headline":"T\u00e9cnicas d&#8217;empaquetatge: el retractilat","datePublished":"2019-01-30T12:25:38+00:00","dateModified":"2019-02-04T14:29:51+00:00","mainEntityOfPage":{"@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/filtext.com\/#organization"},"image":{"@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage"},"thumbnailUrl":"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg","keywords":["Filtext98","Maquinaria Externa"],"articleSection":["Blog","Corporatiu"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#respond"]}]},{"@type":"WebPage","@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge","url":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge","name":"T\u00e8cniques d'Empaquetatge | El Proc\u00e9s de Retractilat | Filtext","isPartOf":{"@id":"https:\/\/filtext.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage"},"image":{"@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage"},"thumbnailUrl":"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg","datePublished":"2019-01-30T12:25:38+00:00","dateModified":"2019-02-04T14:29:51+00:00","description":"El retractilat \u00e9s una de les t\u00e8cniques d'embalatge m\u00e9s usades en el m\u00f3n del packaging. Existeixen nombroses t\u00e8cniques segons la finalitat del client.","breadcrumb":{"@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#primaryimage","url":"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg","contentUrl":"https:\/\/filtext.com\/wp-content\/uploads\/2019\/01\/IMG_20180625_114838_1.jpg","width":4000,"height":3000,"caption":"t\u00e8cniques d'empaquetat"},{"@type":"BreadcrumbList","@id":"http:\/\/filtext.com\/ca\/blog\/tecniques-empaquetatge#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/filtext.com\/ca"},{"@type":"ListItem","position":2,"name":"T\u00e9cnicas d&#8217;empaquetatge: el retractilat"}]},{"@type":"WebSite","@id":"https:\/\/filtext.com\/#website","url":"https:\/\/filtext.com\/","name":"Filtext","description":"","publisher":{"@id":"https:\/\/filtext.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filtext.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/filtext.com\/#organization","name":"Filtext98","url":"https:\/\/filtext.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/filtext.com\/#\/schema\/logo\/image\/","url":"https:\/\/filtext.com\/wp-content\/uploads\/2019\/02\/Logo-Filtext.png","contentUrl":"https:\/\/filtext.com\/wp-content\/uploads\/2019\/02\/Logo-Filtext.png","width":300,"height":88,"caption":"Filtext98"},"image":{"@id":"https:\/\/filtext.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filtext.com\/#\/schema\/person\/8661f6ef084de4ea654250e1bc9b0391","name":"Filtext","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/filtext.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a4ee48e540dc455f239742316dc3194?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a4ee48e540dc455f239742316dc3194?s=96&d=mm&r=g","caption":"Filtext"}}]}},"_links":{"self":[{"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/posts\/2678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/comments?post=2678"}],"version-history":[{"count":2,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/posts\/2678\/revisions"}],"predecessor-version":[{"id":2687,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/posts\/2678\/revisions\/2687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/media\/2637"}],"wp:attachment":[{"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/media?parent=2678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/categories?post=2678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filtext.com\/ca\/wp-json\/wp\/v2\/tags?post=2678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}